{"id":45260,"date":"2025-08-28T16:42:10","date_gmt":"2025-08-28T22:42:10","guid":{"rendered":"https:\/\/contextoanalisisperiodistico.com\/index.php\/2025\/08\/28\/con-inversion-de-mas-de-8-mdp-salomon-jara-entrega-mobiliario-a-60-escuelas-de-la-sierra-de-juarez\/"},"modified":"2025-08-28T16:42:10","modified_gmt":"2025-08-28T22:42:10","slug":"con-inversion-de-mas-de-8-mdp-salomon-jara-entrega-mobiliario-a-60-escuelas-de-la-sierra-de-juarez","status":"publish","type":"post","link":"https:\/\/contextoanalisisperiodistico.com\/index.php\/2025\/08\/28\/con-inversion-de-mas-de-8-mdp-salomon-jara-entrega-mobiliario-a-60-escuelas-de-la-sierra-de-juarez\/","title":{"rendered":"Con inversi\u00f3n de m\u00e1s de 8 mdp, Salom\u00f3n Jara entrega mobiliario a 60 escuelas de la Sierra de Ju\u00e1rez"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n\n<p>\u2022 Estos apoyos favorecen a m\u00e1s de 2 mil estudiantes y son el resultado de un gobierno humanista y cercano a las familias oaxaque\u00f1as<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01093297077226017294136-300x200.jpg\" alt=\"\" class=\"wp-image-45259\" srcset=\"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01093297077226017294136-300x200.jpg 300w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01093297077226017294136-768x512.jpg 768w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01093297077226017294136.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01118538902442276688922-1024x683.jpg\" alt=\"\" class=\"wp-image-45257\" srcset=\"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01118538902442276688922-1024x683.jpg 1024w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01118538902442276688922-300x200.jpg 300w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01118538902442276688922-768x512.jpg 768w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01118538902442276688922.jpg 1491w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01102919032436468984231-300x200.jpg\" alt=\"\" class=\"wp-image-45258\" srcset=\"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01102919032436468984231-300x200.jpg 300w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01102919032436468984231-768x511.jpg 768w, https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/img-20250828-wa01102919032436468984231.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>San Melchor Betaza, Oax. 28 de agosto de 2025.- Con una inversi\u00f3n hist\u00f3rica por 8 millones 172 mil pesos para impulsar la educaci\u00f3n de nueve municipios de la Sierra de Ju\u00e1rez, el Gobernador Salom\u00f3n Jara Cruz entreg\u00f3 mobiliario escolar a 60 escuelas, a las cuales asisten 2 mil 875 alumnas y alumnos de nivel b\u00e1sico.<\/p>\n\n\n\n<p>Ante la Presidenta Honoraria del Sistema DIF Oaxaca, Irma Bola\u00f1os Quijano, autoridades municipales y comit\u00e9s de madres y padres de familia; el Mandatario estatal indic\u00f3 que estos apoyos, nunca antes dados, son el resultado de conocer y atender en territorio, las necesidades de las poblaciones, que ahora se traducen en acciones humanistas.<\/p>\n\n\n\n<p>\u201cNo solamente se respalda a la educaci\u00f3n con equipamiento, sino tambi\u00e9n con la construcci\u00f3n y mejoramiento de aulas, bibliotecas, auditorios y techados para que la entidad salga adelante. \u00a1Oaxaca no puede quedarse atr\u00e1s, no puede quedarse abajo, no puede quedarse en el olvido, tiene que salir adelante!\u201d, precis\u00f3.<\/p>\n\n\n\n<p>En su oportunidad, el director del Instituto Estatal de Educaci\u00f3n P\u00fablica de Oaxaca (IEEPO), Emilio Montero P\u00e9rez expuso que las escuelas beneficiadas se ubican en los municipios de Villa Hidalgo Yalalag, San Melchor Betaza, San Andr\u00e9s Ya\u00e1, San Francisco Cajonos, San Mateo Cajonos, San Pablo Yaganiza, San Pedro Cajonos, Santo Domingo Xagac\u00eda y Totontepec Villa de Morelos.<\/p>\n\n\n\n<p>Resalt\u00f3 que, ante las gestiones de Jara Cruz, en todo el estado se entregan apoyos a 11 mil 630 escuelas, con una inversi\u00f3n de mil 800 millones de pesos, cifra nunca antes registrada.<\/p>\n\n\n\n<p>En representaci\u00f3n de los planteles beneficiados, el director de la escuela Secundaria General, Alier Uriel Santiago Galindo agradeci\u00f3 la entrega de este mobiliario en favor de los escolares oaxaque\u00f1os.<\/p>\n\n\n\n<p>-0-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Estos apoyos favorecen a m\u00e1s de 2 mil estudiantes y son el resultado de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":45256,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[303],"jetpack_sharing_enabled":true,"featured_image_urls":{"full":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg",900,600,false],"thumbnail":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112-150x150.jpg",150,150,true],"medium":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112-300x200.jpg",300,200,true],"medium_large":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112-768x512.jpg",640,427,true],"large":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg",640,427,false],"1536x1536":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg",900,600,false],"2048x2048":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg",900,600,false],"covernews-slider-full":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg",900,600,false],"covernews-slider-center":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112-800x500.jpg",800,500,true],"covernews-featured":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg",900,600,false],"covernews-medium":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112-540x340.jpg",540,340,true],"covernews-medium-square":["https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112-400x250.jpg",400,250,true]},"author_info":{"display_name":"Mario Gir\u00f3n","author_link":"https:\/\/contextoanalisisperiodistico.com\/index.php\/author\/director\/"},"category_info":"<a href=\"https:\/\/contextoanalisisperiodistico.com\/index.php\/category\/municipios\/\" rel=\"category tag\">Municipios<\/a>","tag_info":"Municipios","comment_count":"0","jetpack_featured_media_url":"https:\/\/contextoanalisisperiodistico.com\/wp-content\/uploads\/2025\/08\/IMG-20250828-WA0112.jpg","_links":{"self":[{"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/posts\/45260"}],"collection":[{"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/comments?post=45260"}],"version-history":[{"count":0,"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/posts\/45260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/media\/45256"}],"wp:attachment":[{"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/media?parent=45260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/categories?post=45260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/contextoanalisisperiodistico.com\/index.php\/wp-json\/wp\/v2\/tags?post=45260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}